{"id":23081,"date":"2022-08-11T12:16:08","date_gmt":"2022-08-11T10:16:08","guid":{"rendered":"https:\/\/www.pharmathek.com\/?page_id=23081"},"modified":"2026-07-02T16:19:11","modified_gmt":"2026-07-02T14:19:11","slug":"pharmacie-metanopoli","status":"publish","type":"page","link":"https:\/\/www.pharmathek.com\/fr\/pharmacie-metanopoli\/","title":{"rendered":"Pharmacie Metanopoli"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=\u00a0\u00bbstretch_row_content\u00a0\u00bb equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb bg_type=\u00a0\u00bbbg_color\u00a0\u00bb bg_override=\u00a0\u00bbfull\u00a0\u00bb bg_color_value=\u00a0\u00bb#eeeeef\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1523960338488{padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_single_image image=\u00a0\u00bb4895&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1523960343032{padding-right: 100px !important;padding-left: 100px !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space]<div id=\"ultimate-heading-9016a5723951a3ff\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-9016a5723951a3ff uvc-5790 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-9016a5723951a3ff p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><p style=\"--font-weight:theme;\">PHARMACIE METANOPOLI<\/p><\/div><\/div>[vc_empty_space][vc_column_text el_class=\u00a0\u00bbtext-justify\u00a0\u00bb]La Pharmacie Metanopoli a install\u00e9 un robot Pharmathek.<\/p>\n<p>Le choix du propri\u00e9taire, le Dr Mulas, d&rsquo;installer un entrep\u00f4t robotis\u00e9 est d\u00fb au d\u00e9sir de rendre la gestion de l&rsquo;entrep\u00f4t plus simple et plus rapide.<\/p>\n<p>Compte tenu du haut niveau de personnalisation des solutions Pharmathek, le m\u00e9decin a d\u00e9cid\u00e9 de personnaliser le robot d&rsquo;un point de vue esth\u00e9tique en choisissant d&rsquo;avoir des panneaux de couleur orange.<\/p>\n<p>Cependant, la couleur n&rsquo;est pas visible pour les utilisateurs de la pharmacie car le robot \u00e9tait plac\u00e9 derri\u00e8re le comptoir des ordonnances, mais couvert par des affichages dans la pharmacie avant m\u00eame son automatisation. Les exposants ont \u00e9t\u00e9 modifi\u00e9s de mani\u00e8re appropri\u00e9e afin d&rsquo;ins\u00e9rer les sorties du robot.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content\u00a0\u00bb equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb bg_type=\u00a0\u00bbbg_color\u00a0\u00bb bg_override=\u00a0\u00bbfull\u00a0\u00bb bg_color_value=\u00a0\u00bb#eeeeef\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1524126670718{padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-lg\u00a0\u00bb el_class=\u00a0\u00bbfull-width-no-padding\u00a0\u00bb][vc_single_image image=\u00a0\u00bb4895&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][vc_empty_space]<div id=\"ultimate-heading-22126a5723951a4a2\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-22126a5723951a4a2 uvc-7126 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-22126a5723951a4a2 p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><p style=\"--font-weight:theme;\">PHARMACIE METANOPOLI<\/p><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-22126a5723951a4a2 .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><\/p>\n<p><\/div><\/div>[vc_empty_space][vc_column_text el_class=\u00a0\u00bbtext-justify\u00a0\u00bb]La Pharmacie Metanopoli a install\u00e9 un robot Pharmathek.<\/p>\n<p>Le choix du propri\u00e9taire, le Dr Mulas, d&rsquo;installer un entrep\u00f4t robotis\u00e9 est d\u00fb au d\u00e9sir de rendre la gestion de l&rsquo;entrep\u00f4t plus simple et plus rapide.<\/p>\n<p>Compte tenu du haut niveau de personnalisation des solutions Pharmathek, le m\u00e9decin a d\u00e9cid\u00e9 de personnaliser le robot d&rsquo;un point de vue esth\u00e9tique en choisissant d&rsquo;avoir des panneaux de couleur orange.<\/p>\n<p>Cependant, la couleur n&rsquo;est pas visible pour les utilisateurs de la pharmacie car le robot \u00e9tait plac\u00e9 derri\u00e8re le comptoir des ordonnances, mais couvert par des affichages dans la pharmacie avant m\u00eame son automatisation. Les exposants ont \u00e9t\u00e9 modifi\u00e9s de mani\u00e8re appropri\u00e9e afin d&rsquo;ins\u00e9rer les sorties du robot.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column offset=\u00a0\u00bbvc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb4899&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space]<div id=\"ultimate-heading-85546a5723951a520\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-85546a5723951a520 uvc-4299 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-85546a5723951a520 p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><p style=\"--font-weight:theme;\">LA PAROLE AU PHARMACIEN<\/p><\/div><\/div>[vc_empty_space][vc_column_text el_class=\u00a0\u00bbtext-justify\u00a0\u00bb]<\/p>\n<h4>Docteur Mulas, qu&rsquo;est-ce qui vous a amen\u00e9 \u00e0 d\u00e9cider d&rsquo;automatiser votre officine ?<\/h4>\n<p>La n\u00e9cessit\u00e9 d&rsquo;all\u00e9ger et d&rsquo;acc\u00e9l\u00e9rer la gestion des entrep\u00f4ts et donc de lib\u00e9rer les magasiniers des t\u00e2ches les plus fastidieuses et r\u00e9p\u00e9titives.<\/p>\n<p>Apr\u00e8s l\u2019installation du robot, j&rsquo;ai aussi pu voir d&rsquo;autres avantages tr\u00e8s appr\u00e9ci\u00e9s : maintenant dans la pharmacie il y a plus d&rsquo;ordre, plus de pr\u00e9cision, plus de s\u00e9curit\u00e9 dans les stocks, un meilleur affichage au fond du comptoir et une image d&rsquo;une pharmacie plus moderne.<\/p>\n<p>&nbsp;<\/p>\n<h4>Qu&rsquo;est-ce qui vous a amen\u00e9 \u00e0 choisir de faire confiance \u00e0 Pharmathek pour l&rsquo;automatisation de la pharmacie ?<\/h4>\n<p>L&rsquo;exp\u00e9rience pr\u00e9c\u00e9dente positive avec le groupe Th.Kohl \u00e0 travers la soci\u00e9t\u00e9 du groupe sp\u00e9cialis\u00e9e dans le mobilier pour pharmacies.<\/p>\n<p>J&rsquo;\u00e9tais tellement content de l&rsquo;autre soci\u00e9t\u00e9 du groupe que je n&rsquo;ai m\u00eame pas pris la peine de contacter d&rsquo;autres soci\u00e9t\u00e9s pour l&rsquo;automatisation. Connaissant la fiabilit\u00e9 de Th.Kohl, je savais que je pouvais aussi faire confiance \u00e0 Pharmathek.<\/p>\n<p>Je suis all\u00e9 sur la confiance et le r\u00e9sultat me pla\u00eet.<\/p>\n<p>&nbsp;<\/p>\n<h4>Que pensez-vous du r\u00e9sultat ?<\/h4>\n<p>Je m&rsquo;entends bien avec le robot, il a une excellente convivialit\u00e9. En fait, m\u00eame les membres les moins f\u00e9rus de technologie de notre personnel n&rsquo;ont eu aucune difficult\u00e9 \u00e0 apprendre \u00e0 l&rsquo;utiliser.<\/p>\n<p>De plus, un plus que j&rsquo;ai appr\u00e9ci\u00e9 \u00e9tait la possibilit\u00e9 de personnaliser le robot \u00e9galement d&rsquo;un point de vue esth\u00e9tique, et en fait j&rsquo;ai d\u00e9cid\u00e9 de le faire peindre en orange, une couleur que j&rsquo;aime beaucoup.<\/p>\n<p>Et j&rsquo;\u00e9tais \u00e9galement satisfait de l&rsquo;assistance.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column offset=\u00a0\u00bbvc_hidden-lg\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb4899&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space]<div id=\"ultimate-heading-10466a5723951a58b\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-10466a5723951a58b uvc-4076 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-10466a5723951a58b p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><p style=\"--font-weight:theme;\">LA PAROLE AU PHARMACIEN<\/p><\/div><\/div>[vc_empty_space][vc_column_text el_class=\u00a0\u00bbtext-justify\u00a0\u00bb]<\/p>\n<h4>Docteur Mulas, qu&rsquo;est-ce qui vous a amen\u00e9 \u00e0 d\u00e9cider d&rsquo;automatiser votre officine ?<\/h4>\n<p>La n\u00e9cessit\u00e9 d&rsquo;all\u00e9ger et d&rsquo;acc\u00e9l\u00e9rer la gestion des entrep\u00f4ts et donc de lib\u00e9rer les magasiniers des t\u00e2ches les plus fastidieuses et r\u00e9p\u00e9titives.<\/p>\n<p>Apr\u00e8s l\u2019installation du robot, j&rsquo;ai aussi pu voir d&rsquo;autres avantages tr\u00e8s appr\u00e9ci\u00e9s : maintenant dans la pharmacie il y a plus d&rsquo;ordre, plus de pr\u00e9cision, plus de s\u00e9curit\u00e9 dans les stocks, un meilleur affichage au fond du comptoir et une image d&rsquo;une pharmacie plus moderne.<\/p>\n<p>&nbsp;<\/p>\n<h4>Qu&rsquo;est-ce qui vous a amen\u00e9 \u00e0 choisir de faire confiance \u00e0 Pharmathek pour l&rsquo;automatisation de la pharmacie ?<\/h4>\n<p>L&rsquo;exp\u00e9rience pr\u00e9c\u00e9dente positive avec le groupe Th.Kohl \u00e0 travers la soci\u00e9t\u00e9 du groupe sp\u00e9cialis\u00e9e dans le mobilier pour pharmacies.<\/p>\n<p>J&rsquo;\u00e9tais tellement content de l&rsquo;autre soci\u00e9t\u00e9 du groupe que je n&rsquo;ai m\u00eame pas pris la peine de contacter d&rsquo;autres soci\u00e9t\u00e9s pour l&rsquo;automatisation. Connaissant la fiabilit\u00e9 de Th.Kohl, je savais que je pouvais aussi faire confiance \u00e0 Pharmathek.<\/p>\n<p>Je suis all\u00e9 sur la confiance et le r\u00e9sultat me pla\u00eet.<\/p>\n<p>&nbsp;<\/p>\n<h4>Que pensez-vous du r\u00e9sultat ?<\/h4>\n<p>Je m&rsquo;entends bien avec le robot, il a une excellente convivialit\u00e9. En fait, m\u00eame les membres les moins f\u00e9rus de technologie de notre personnel n&rsquo;ont eu aucune difficult\u00e9 \u00e0 apprendre \u00e0 l&rsquo;utiliser.<\/p>\n<p>De plus, un plus que j&rsquo;ai appr\u00e9ci\u00e9 \u00e9tait la possibilit\u00e9 de personnaliser le robot \u00e9galement d&rsquo;un point de vue esth\u00e9tique, et en fait j&rsquo;ai d\u00e9cid\u00e9 de le faire peindre en orange, une couleur que j&rsquo;aime beaucoup.<\/p>\n<p>Et j&rsquo;\u00e9tais \u00e9galement satisfait de l&rsquo;assistance.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb bg_type=\u00a0\u00bbbg_color\u00a0\u00bb bg_override=\u00a0\u00bbfull\u00a0\u00bb bg_color_value=\u00a0\u00bb#eeeeef\u00a0\u00bb][vc_column offset=\u00a0\u00bbvc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb]<div id=\"ultimate-heading-18166a5723951a605\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-18166a5723951a605 uvc-8104 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-18166a5723951a605 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;\">GALERIE<\/h2><\/div><\/div>[vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_masonry_media_grid element_width=\u00a0\u00bb3&Prime; gap=\u00a0\u00bb10&Prime; grid_id=\u00a0\u00bbvc_gid:1660212496902-6b8dc2f5-8379-4&Prime; include=\u00a0\u00bb4912,4916,4932,4936,4920,4924,4940,4928&Prime;][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb bg_type=\u00a0\u00bbbg_color\u00a0\u00bb bg_override=\u00a0\u00bbfull\u00a0\u00bb bg_color_value=\u00a0\u00bb#eeeeef\u00a0\u00bb][vc_column offset=\u00a0\u00bbvc_hidden-lg\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb]<div id=\"ultimate-heading-18326a5723951a67e\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-18326a5723951a67e uvc-2281 head-section-title uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-18326a5723951a67e h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;\">GALERIE<\/h2><\/div><\/div>[vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_masonry_media_grid element_width=\u00a0\u00bb3&Prime; gap=\u00a0\u00bb10&Prime; grid_id=\u00a0\u00bbvc_gid:1660212496906-f57df3a1-1cbe-4&Prime; include=\u00a0\u00bb4912,4940,4916,4936,4932,4920,4924,4928&Prime;][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb bg_type=\u00a0\u00bbimage\u00a0\u00bb parallax_style=\u00a0\u00bbvcpb-default\u00a0\u00bb bg_image_new=\u00a0\u00bbid^1166|url^http:\/\/www.pharmathek.com\/wp-content\/uploads\/2018\/03\/farmacia-specifiche-background.jpg|caption^null|alt^null|title^farmacia-specifiche-background|description^null\u00a0\u00bb bg_image_repeat=\u00a0\u00bbno-repeat\u00a0\u00bb bg_override=\u00a0\u00bbfull\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb]<div id=\"ultimate-heading-14006a5723951a6f6\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-14006a5723951a6f6 uvc-9404 head-section-title text-white uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-14006a5723951a6f6 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;\">LE PROJET<\/h2><\/div><\/div>[vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci\u00a0\u00bb]SOLUTIONS PHARMATHEK[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci-valori\u00a0\u00bb]SINTESI + PHARMALOAD + EUCLID3D[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci\u00a0\u00bb]DIMENSIONS ROBOT[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci-valori\u00a0\u00bb]<\/p>\n<p>L 6.047 x H 2.600 mm<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci\u00a0\u00bb]CAPACIT\u00c9 BO\u00ceTES[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci-valori\u00a0\u00bb]12.300[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci\u00a0\u00bb]POSITION ROBOT PAR RAPPORT AU COMPTOIR[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci-valori\u00a0\u00bb]DERRI\u00c8RE LE COMPTOIR[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci\u00a0\u00bb]PRODUITS EN MOUVEMENT[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text el_class=\u00a0\u00bbprogetto-voci-valori\u00a0\u00bb]entre 500 et 1000[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator color=\u00a0\u00bbwhite\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb][vc_column el_class=\u00a0\u00bbfull-width-no-padding\u00a0\u00bb][vc_single_image image=\u00a0\u00bb4903&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#default-btn-0e4e87e5e968b404cd830fa571b9ffc3.ico-right-side > i {\n  margin-right: 0px;\n  margin-left: 8px;\n}\n#default-btn-0e4e87e5e968b404cd830fa571b9ffc3 > i {\n  margin-right: 8px;\n}\n<\/style><div class=\"btn-align-center\"><a href=\"https:\/\/www.pharmathek.com\/fr\/installations\/\" class=\"default-btn-shortcode dt-btn dt-btn-l link-hover-off weight-300 full-width-btn \" id=\"default-btn-0e4e87e5e968b404cd830fa571b9ffc3\" title=\"Installations\"><span>Retour \u00e0 la liste des installations<\/span><\/a><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>S. Donato Milanese (Italie)<\/p>\n","protected":false},"author":3,"featured_media":4907,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-23081","page","type-page","status-publish","has-post-thumbnail","hentry","category-pharmacies","description-off"],"_links":{"self":[{"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/pages\/23081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/comments?post=23081"}],"version-history":[{"count":4,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/pages\/23081\/revisions"}],"predecessor-version":[{"id":115065,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/pages\/23081\/revisions\/115065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/media\/4907"}],"wp:attachment":[{"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/media?parent=23081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/categories?post=23081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pharmathek.com\/fr\/wp-json\/wp\/v2\/tags?post=23081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}